{"id":4343,"date":"2026-08-31T09:20:55","date_gmt":"2026-08-31T01:20:55","guid":{"rendered":"https:\/\/ecmicrophones.com\/?post_type=product&#038;p=4343"},"modified":"2026-08-31T09:26:01","modified_gmt":"2026-08-31T01:26:01","slug":"unidirectional-ecm-mic-with-silicone-sleeve-for-vocal-broadcasting","status":"publish","type":"product","link":"https:\/\/ecmicrophones.com\/pt\/unidirectional-ecm-mic-with-silicone-sleeve-for-vocal-broadcasting\/","title":{"rendered":"Microfone ECM unidirecional com capa de silicone para canto e radiodifus\u00e3o"},"content":{"rendered":"<h2 class=\"text-start\">Vis\u00e3o geral<\/h2>\n<p class=\"text-start\">O <strong>ECM-B1812UL45-26513<\/strong> \u00e9 um produto de n\u00edvel profissional <strong>microfone condensador unidirecional com eletr\u00e9to traseiro<\/strong> projetado especificamente para <strong>apresenta\u00e7\u00e3o vocal, transmiss\u00e3o ao vivo e transmiss\u00e3o<\/strong>. Seu <strong>padr\u00e3o de capta\u00e7\u00e3o cardi\u00f3ide (unidirecional)<\/strong> rejeita eficazmente o ru\u00eddo ambiente fora do eixo, garantindo uma capta\u00e7\u00e3o focada na voz do usu\u00e1rio com o m\u00ednimo de colora\u00e7\u00e3o ac\u00fastica do ambiente \u2014 perfeito para est\u00fadios dom\u00e9sticos, podcasting, sistemas de karaok\u00ea e uso em palco.<\/p>\n<h2 class=\"pt-4 text-start\">Principais caracter\u00edsticas<\/h2>\n<ul class=\"text-start\">\n<li><strong>Manga de silicone integrada<\/strong> \u2013 A manga oca de silicone proporciona isolamento eficaz contra vibra\u00e7\u00f5es, prote\u00e7\u00e3o mec\u00e2nica e veda\u00e7\u00e3o ac\u00fastica, garantindo uma montagem est\u00e1vel em diversos compartimentos. O di\u00e2metro do n\u00facleo do microfone sem a manga \u00e9 de 16 mm; com a manga de silicone, o di\u00e2metro total aumenta para 18 mm.<\/li>\n<li><strong>Padr\u00e3o de capta\u00e7\u00e3o unidirecional (cardioide)<\/strong> \u2013 Concentra-se no som proveniente da frente, ao mesmo tempo em que rejeita o ru\u00eddo proveniente dos lados e da parte traseira, sendo ideal para o isolamento vocal.<\/li>\n<li><strong>Alta sensibilidade (-45 \u00b1 2 dB)<\/strong> \u2013 Proporciona sa\u00edda consistente em todas as unidades com RL=680 \u03a9 e Vs=1,5 V, garantindo um desempenho confi\u00e1vel.<\/li>\n<li><strong>Alta rela\u00e7\u00e3o sinal-ru\u00eddo (70 dB t\u00edpico, ponderada A)<\/strong> \u2013 Oferece um caminho de sinal limpo e com baixo ru\u00eddo, que preserva a faixa din\u00e2mica e as nuances vocais.<\/li>\n<li><strong>Resposta de graves profunda e potente<\/strong> \u2013 A resposta de frequ\u00eancia otimizada confere calor, corpo e presen\u00e7a aos vocais.<\/li>\n<li><strong>Altas frequ\u00eancias n\u00edtidas e bem definidas<\/strong> \u2013 Mant\u00e9m clareza e detalhes excepcionais para vocais n\u00edtidos e compreens\u00edveis.<\/li>\n<li><strong>Alto SPL m\u00e1ximo (110 dB, THD \u2264 31 TP3T)<\/strong> \u2013 Lida tanto com passagens suaves quanto com cantos em volume alto, sem distor\u00e7\u00e3o nem clipping.<\/li>\n<li><strong>Ampla faixa de tens\u00e3o de opera\u00e7\u00e3o (1,0\u201310,0 V CC)<\/strong> \u2013 Compat\u00edvel com uma ampla variedade de interfaces de \u00e1udio, mixers e dispositivos port\u00e1teis.<\/li>\n<li><strong>Tens\u00e3o de opera\u00e7\u00e3o padr\u00e3o (1,5 V CC)<\/strong> \u2013 Otimizado para desempenho consistente em condi\u00e7\u00f5es nominais.<\/li>\n<li><strong>Baixo consumo de corrente (\u2264500 \u00b5A)<\/strong> \u2013 Ideal para aplica\u00e7\u00f5es alimentadas por bateria e com baixo consumo de energia.<\/li>\n<li><strong>Baixa imped\u00e2ncia de sa\u00edda (\u2264680 \u03a9)<\/strong> \u2013 Garante uma transmiss\u00e3o est\u00e1vel do sinal com o m\u00ednimo de interfer\u00eancia.<\/li>\n<li><strong>Caracter\u00edsticas de queda de tens\u00e3o (m\u00e1x. -3 dB, Vs = 1,5 V a 1,0 V)<\/strong> \u2013 Mant\u00e9m um desempenho est\u00e1vel mesmo com flutua\u00e7\u00f5es de tens\u00e3o.<\/li>\n<\/ul>\n<h2 class=\"pt-4 text-start\">Especifica\u00e7\u00f5es t\u00e9cnicas<\/h2>\n<ul class=\"text-start\">\n<li><strong>Modelo:<\/strong> ECM-B1812UL45-26513<\/li>\n<li><strong>Caracter\u00edstica direcional:<\/strong> Unidirecional (cardioide)<\/li>\n<li><strong>Sensibilidade:<\/strong> -45 \u00b1 2 dB (RL = 680 \u03a9, Vs = 1,5 V, @f = 1 kHz, Pin = 1 Pa, 0 dB = 1 V\/Pa, L = 50 cm)<\/li>\n<li><strong>Imped\u00e2ncia de sa\u00edda:<\/strong> 680 \u03a9 (m\u00e1x.)<\/li>\n<li><strong>Rela\u00e7\u00e3o sinal-ru\u00eddo:<\/strong> 70 dB (t\u00edpico, rede com pondera\u00e7\u00e3o A)<\/li>\n<li><strong>N\u00edvel m\u00e1ximo de press\u00e3o sonora de entrada:<\/strong> 110 dB (THD \u2264 31 TP3T)<\/li>\n<li><strong>Tens\u00e3o nominal de opera\u00e7\u00e3o:<\/strong> 1,5V CC<\/li>\n<li><strong>Faixa de tens\u00e3o de opera\u00e7\u00e3o:<\/strong> 1,0\u201310,0 V CC<\/li>\n<li><strong>Caracter\u00edsticas de queda de tens\u00e3o:<\/strong> -3 dB (m\u00e1x., Vs = 1,5 V a 1,0 V CC)<\/li>\n<li><strong>Consumo atual:<\/strong> 500 \u00b5A (m\u00e1x.)<\/li>\n<li><strong>Resposta de frequ\u00eancia:<\/strong> Veja a curva de resposta em frequ\u00eancia t\u00edpica (Fig. 2)<\/li>\n<li><strong>Circuito de teste padr\u00e3o:<\/strong> RL = 680 \u03a9, Vs = 1,5 V CC (ver Fig. 1)<\/li>\n<li><strong>Dimens\u00f5es:<\/strong> Di\u00e2metro do n\u00facleo do microfone sem revestimento: 16 mm; com manga de silicone: 18 mm (acrescenta 1 mm de cada lado).<\/li>\n<\/ul>\n<h2 class=\"pt-4 text-start\">Confiabilidade e durabilidade ambiental<\/h2>\n<ul class=\"text-start\">\n<li><strong>Teste de alta temperatura:<\/strong> +80 \u00b0C por 100 horas, varia\u00e7\u00e3o de sensibilidade \u2264 \u00b13 dB<\/li>\n<li><strong>Teste de baixa temperatura:<\/strong> -40 \u00b0C por 100 horas, varia\u00e7\u00e3o de sensibilidade \u2264 \u00b13 dB<\/li>\n<li><strong>Teste de umidade e calor:<\/strong> +55 \u00b0C, 85% de umidade relativa do ar por 100 horas, varia\u00e7\u00e3o de sensibilidade \u2264\u00b13 dB<\/li>\n<li><strong>Teste de choque t\u00e9rmico:<\/strong> +80 \u00b0C 0,5 h \u2192 temperatura ambiente 1 h \u2192 -40 \u00b0C 0,5 h \u2192 temperatura ambiente 1 h, 10 ciclos, varia\u00e7\u00e3o de sensibilidade \u2264\u00b13 dB<\/li>\n<li><strong>Teste de vibra\u00e7\u00e3o:<\/strong> 10-55 Hz, amplitude de 1,52 mm, 2 horas por dire\u00e7\u00e3o X\/Y\/Z, varia\u00e7\u00e3o de sensibilidade \u2264\u00b13 dB<\/li>\n<li><strong>Teste de queda:<\/strong> Queda de 1,0 m sobre piso de m\u00e1rmore, 5 vezes sem embalagem, varia\u00e7\u00e3o de sensibilidade \u2264\u00b13 dB<\/li>\n<li><strong>Temperatura de armazenamento:<\/strong> -35 \u00b0C a +60 \u00b0C<\/li>\n<li><strong>Temperatura de opera\u00e7\u00e3o:<\/strong> -35 \u00b0C a +60 \u00b0C<\/li>\n<\/ul>\n<h2 class=\"pt-4 text-start\">Orienta\u00e7\u00f5es para soldagem e manuseio<\/h2>\n<ul class=\"text-start\">\n<li>Temperatura de soldagem: 360 \u00b1 10 \u00b0C; tempo de soldagem: \u2264 3 segundos<\/li>\n<li>Os operadores, os dispositivos de fixa\u00e7\u00e3o e o ferro de solda devem estar aterrados estaticamente<\/li>\n<li>Tamanho recomendado do furo na placa de circuito impresso: di\u00e2metro do MIC + 0,05 mm<\/li>\n<li>Altura recomendada para os furos da placa de circuito impresso: Altura MIC \u2013 0,2 mm<\/li>\n<\/ul>\n<p class=\"text-start\">Projetado para oferecer durabilidade e desempenho consistente, o ECM-B1812UL45-26513 \u00e9 a escolha ideal para criadores de conte\u00fado, vocalistas e engenheiros de \u00e1udio que buscam um <strong>microfone de n\u00edvel profissional<\/strong> que oferece <strong>graves profundos e quentes, agudos n\u00edtidos e brilhantes e excelente supress\u00e3o de ru\u00eddo<\/strong> em um pacote robusto e confi\u00e1vel \u2014 agora com o benef\u00edcio adicional de um <strong>manga oca de silicone<\/strong> que amplia o di\u00e2metro de 16 mm para 18 mm, proporcionando melhor isolamento contra vibra\u00e7\u00f5es e uma fixa\u00e7\u00e3o mais segura.<\/p>","protected":false},"excerpt":{"rendered":"<p>Um microfone condensador profissional unidirecional com eletreto traseiro e manga de silicone integrada (que amplia o di\u00e2metro de 16 mm para 18 mm) para isolamento contra vibra\u00e7\u00f5es e fixa\u00e7\u00e3o segura, com padr\u00e3o de capta\u00e7\u00e3o cardi\u00f3ide, sensibilidade de -45 \u00b1 2 dB, SNR de 70 dB, SPL m\u00e1ximo de 110 dB, graves profundos e agudos n\u00edtidos \u2014 ideal para canto, transmiss\u00f5es ao vivo e grava\u00e7\u00f5es em est\u00fadio.<\/p>","protected":false},"featured_media":4346,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[721],"product_cat":[21],"product_tag":[279,779,288,116],"class_list":["post-4343","product","type-product","status-publish","has-post-thumbnail","product_brand-ecmic","product_cat-unidirectional-microphones","product_tag-16mm","product_tag-silicone-sleeve","product_tag-solder-pads","product_tag-vocal","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ecmicrophones.com\/pt\/wp-json\/wp\/v2\/product\/4343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecmicrophones.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ecmicrophones.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ecmicrophones.com\/pt\/wp-json\/wp\/v2\/comments?post=4343"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecmicrophones.com\/pt\/wp-json\/wp\/v2\/media\/4346"}],"wp:attachment":[{"href":"https:\/\/ecmicrophones.com\/pt\/wp-json\/wp\/v2\/media?parent=4343"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ecmicrophones.com\/pt\/wp-json\/wp\/v2\/product_brand?post=4343"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ecmicrophones.com\/pt\/wp-json\/wp\/v2\/product_cat?post=4343"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ecmicrophones.com\/pt\/wp-json\/wp\/v2\/product_tag?post=4343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}